{"id":15,"count":24,"description":"","link":"https:\/\/sibeniktaxi.com\/en\/category\/sibenik\/","name":"\u0160ibenik","slug":"sibenik","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0160ibenik | Taxi \u0160ibenik<\/title>\n<meta name=\"description\" content=\"Saznajte sve informacije o gradu \u0160ibeniku - koja mjesta morate obavezno posjetiti, gdje preno\u0107iti ukoliko ostajete dulje u gradu te kako se zabaviti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sibeniktaxi.com\/en\/category\/sibenik\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0160ibenik | Taxi \u0160ibenik\" \/>\n<meta property=\"og:description\" content=\"Saznajte sve informacije o gradu \u0160ibeniku - koja mjesta morate obavezno posjetiti, gdje preno\u0107iti ukoliko ostajete dulje u gradu te kako se zabaviti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sibeniktaxi.com\/en\/category\/sibenik\/\" \/>\n<meta property=\"og:site_name\" content=\"Taxi \u0160ibenik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sibeniktaxi.com\\\/category\\\/sibenik\\\/\",\"url\":\"https:\\\/\\\/sibeniktaxi.com\\\/category\\\/sibenik\\\/\",\"name\":\"\u0160ibenik | Taxi \u0160ibenik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sibeniktaxi.com\\\/#website\"},\"description\":\"Saznajte sve informacije o gradu \u0160ibeniku - koja mjesta morate obavezno posjetiti, gdje preno\u0107iti ukoliko ostajete dulje u gradu te kako se zabaviti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sibeniktaxi.com\\\/category\\\/sibenik\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sibeniktaxi.com\\\/category\\\/sibenik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Taxi \u0160ibenik\",\"item\":\"https:\\\/\\\/sibeniktaxi.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0160ibenik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sibeniktaxi.com\\\/#website\",\"url\":\"https:\\\/\\\/sibeniktaxi.com\\\/\",\"name\":\"Taxi \u0160ibenik\",\"description\":\"Najbolji Taxi u gradu\",\"publisher\":{\"@id\":\"https:\\\/\\\/sibeniktaxi.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sibeniktaxi.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sibeniktaxi.com\\\/#organization\",\"name\":\"Taxi \u0160ibenik\",\"url\":\"https:\\\/\\\/sibeniktaxi.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sibeniktaxi.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sibeniktaxi.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/cropped-TAXI-DALMACIJA-logo-lav-rose-3.png\",\"contentUrl\":\"https:\\\/\\\/sibeniktaxi.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/cropped-TAXI-DALMACIJA-logo-lav-rose-3.png\",\"width\":\"240\",\"height\":\"116\",\"caption\":\"Taxi \u0160ibenik\"},\"image\":{\"@id\":\"https:\\\/\\\/sibeniktaxi.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sibeniktaxi\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0160ibenik | Taxi \u0160ibenik","description":"Saznajte sve informacije o gradu \u0160ibeniku - koja mjesta morate obavezno posjetiti, gdje preno\u0107iti ukoliko ostajete dulje u gradu te kako se zabaviti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sibeniktaxi.com\/en\/category\/sibenik\/","og_locale":"en_US","og_type":"article","og_title":"\u0160ibenik | Taxi \u0160ibenik","og_description":"Saznajte sve informacije o gradu \u0160ibeniku - koja mjesta morate obavezno posjetiti, gdje preno\u0107iti ukoliko ostajete dulje u gradu te kako se zabaviti.","og_url":"https:\/\/sibeniktaxi.com\/en\/category\/sibenik\/","og_site_name":"Taxi \u0160ibenik","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sibeniktaxi.com\/category\/sibenik\/","url":"https:\/\/sibeniktaxi.com\/category\/sibenik\/","name":"\u0160ibenik | Taxi \u0160ibenik","isPartOf":{"@id":"https:\/\/sibeniktaxi.com\/#website"},"description":"Saznajte sve informacije o gradu \u0160ibeniku - koja mjesta morate obavezno posjetiti, gdje preno\u0107iti ukoliko ostajete dulje u gradu te kako se zabaviti.","breadcrumb":{"@id":"https:\/\/sibeniktaxi.com\/category\/sibenik\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/sibeniktaxi.com\/category\/sibenik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Taxi \u0160ibenik","item":"https:\/\/sibeniktaxi.com\/"},{"@type":"ListItem","position":2,"name":"\u0160ibenik"}]},{"@type":"WebSite","@id":"https:\/\/sibeniktaxi.com\/#website","url":"https:\/\/sibeniktaxi.com\/","name":"Taxi Sibenik","description":"The best Taxi in the city","publisher":{"@id":"https:\/\/sibeniktaxi.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sibeniktaxi.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sibeniktaxi.com\/#organization","name":"Taxi Sibenik","url":"https:\/\/sibeniktaxi.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sibeniktaxi.com\/#\/schema\/logo\/image\/","url":"https:\/\/sibeniktaxi.com\/wp-content\/uploads\/2018\/04\/cropped-TAXI-DALMACIJA-logo-lav-rose-3.png","contentUrl":"https:\/\/sibeniktaxi.com\/wp-content\/uploads\/2018\/04\/cropped-TAXI-DALMACIJA-logo-lav-rose-3.png","width":"240","height":"116","caption":"Taxi \u0160ibenik"},"image":{"@id":"https:\/\/sibeniktaxi.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sibeniktaxi\/"]}]}},"_links":{"self":[{"href":"https:\/\/sibeniktaxi.com\/en\/wp-json\/wp\/v2\/categories\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sibeniktaxi.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sibeniktaxi.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/sibeniktaxi.com\/en\/wp-json\/wp\/v2\/posts?categories=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}